{"id":446,"date":"2018-10-22T11:01:00","date_gmt":"2018-10-22T11:01:00","guid":{"rendered":"https:\/\/blogs.zeiss.com\/intern\/sportsoptics\/hunting\/de\/?p=446"},"modified":"2020-02-21T10:38:29","modified_gmt":"2020-02-21T10:38:29","slug":"wildschwein-schnitzel","status":"publish","type":"post","link":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wildschwein-schnitzel\/","title":{"rendered":"Wildschwein Schnitzel"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Das Rezept zum Herunterladen finden Sie am Ende des Artikels. <\/h2>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/boarschnitzel_450wide.jpg\" alt=\"\" class=\"wp-image-905\" width=\"1000\" height=\"450\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/boarschnitzel_450wide.jpg 1000w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/boarschnitzel_450wide-600x270.jpg 600w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/boarschnitzel_450wide-768x346.jpg 768w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/boarschnitzel_450wide-640x288.jpg 640w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 770px\" \/><\/figure>\n\n\n\n<pre class=\"wp-block-preformatted\"><img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"wp-image-222\" style=\"width: 25px;\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/stopwatch-512.png\" alt=\"\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/stopwatch-512.png 512w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/stopwatch-512-150x150.png 150w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 25px\" \/> 30 Minuten   <img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"wp-image-221\" style=\"width: 25px;\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/servings.png\" alt=\"\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/servings.png 225w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/servings-150x150.png 150w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 25px\" \/> 4 Portionen<\/pre>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Ich mag mein Schnitzel doppelt paniert &#8211; in Butter und Zitrone schwimmend!<\/p><cite>METTE KARIN PETERSEN<\/cite><\/blockquote>\n\n\n\n<p>Die Dr\u00fcckjagd-Saison ist in vollem Gange. Wildschweine sind \u00fcberall und verursachen erhebliche Sch\u00e4den in der Land- und Forstwirtschaft. Gl\u00fccklicherweise ist Wild-schwein sehr cholesterinarm und somit eine ausgezeichnete Alternative zu Rind- und Schweinefleisch. <\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>Zutaten<\/strong><\/p>\n\n\n\n<p><strong>F\u00fcr das Fleisch:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Knochenlose Wildschweinkoteletts<\/li><li>3 Eier<\/li><li>5 Tassen Mehl<\/li><li>10 Tassen Semmelbr\u00f6sel<\/li><li>100gr Butter<\/li><li>Salz und Pfeffer<\/li><li>\u00d6l zum Anbraten<\/li><li>Zitronen<\/li><li>Kapern (optional)<\/li><li>Meerrettich (optional)<\/li><\/ul>\n\n\n\n<p><strong>M\u00f6gliche Beilagen:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Bratkartoffeln<\/li><li>Erbsen <\/li><\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-768x1024.jpeg\" alt=\"\" data-id=\"312\" data-full-url=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-scaled.jpeg\" data-link=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/step_1-0\/\" class=\"wp-image-312\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-768x1024.jpeg 768w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-450x600.jpeg 450w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-1152x1536.jpeg 1152w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-1536x2048.jpeg 1536w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-640x853.jpeg 640w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-1024x1365.jpeg 1024w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-1200x1600.jpeg 1200w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.0-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-768x1024.jpeg\" alt=\"\" data-id=\"304\" data-full-url=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-scaled.jpeg\" data-link=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/dav\/\" class=\"wp-image-304\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-768x1024.jpeg 768w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-450x600.jpeg 450w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-1152x1536.jpeg 1152w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-1536x2048.jpeg 1536w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-640x853.jpeg 640w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-1024x1365.jpeg 1024w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-1200x1600.jpeg 1200w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_1.1-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-768x1024.jpeg\" alt=\"\" data-id=\"305\" data-full-url=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-scaled.jpeg\" data-link=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/step_2-0\/\" class=\"wp-image-305\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-768x1024.jpeg 768w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-450x600.jpeg 450w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-1152x1536.jpeg 1152w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-1536x2048.jpeg 1536w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-640x853.jpeg 640w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-1024x1365.jpeg 1024w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-1200x1600.jpeg 1200w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.0-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-768x1024.jpeg\" alt=\"\" data-id=\"306\" data-full-url=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-scaled.jpeg\" data-link=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/step_2-2\/\" class=\"wp-image-306\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-768x1024.jpeg 768w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-450x600.jpeg 450w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-1152x1536.jpeg 1152w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-1536x2048.jpeg 1536w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-640x853.jpeg 640w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-1024x1365.jpeg 1024w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-1200x1600.jpeg 1200w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_2.2-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-768x1024.jpeg\" alt=\"\" data-id=\"307\" data-full-url=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-scaled.jpeg\" data-link=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/step_3-0\/\" class=\"wp-image-307\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-768x1024.jpeg 768w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-450x600.jpeg 450w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-1152x1536.jpeg 1152w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-1536x2048.jpeg 1536w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-640x853.jpeg 640w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-1024x1365.jpeg 1024w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-1200x1600.jpeg 1200w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.0-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-768x1024.jpeg\" alt=\"\" data-id=\"308\" data-full-url=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-scaled.jpeg\" data-link=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/step_3-1\/\" class=\"wp-image-308\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-768x1024.jpeg 768w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-450x600.jpeg 450w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-1152x1536.jpeg 1152w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-1536x2048.jpeg 1536w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-640x853.jpeg 640w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-1024x1365.jpeg 1024w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-1200x1600.jpeg 1200w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_3.1-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-768x1024.jpeg\" alt=\"\" data-id=\"309\" data-full-url=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-scaled.jpeg\" data-link=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/step_4\/\" class=\"wp-image-309\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-768x1024.jpeg 768w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-450x600.jpeg 450w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-1152x1536.jpeg 1152w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-1536x2048.jpeg 1536w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-640x853.jpeg 640w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-1024x1365.jpeg 1024w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-1200x1600.jpeg 1200w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_4-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909-768x1024.jpeg\" alt=\"\" data-id=\"310\" data-full-url=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909.jpeg\" data-link=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/step_5-0\/\" class=\"wp-image-310 is-layout-flex wp-block-gallery-is-layout-flex\" srcset=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909-768x1024.jpeg 768w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909-450x600.jpeg 450w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909-1152x1536.jpeg 1152w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909-1536x2048.jpeg 1536w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909-640x853.jpeg 640w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909-1024x1365.jpeg 1024w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909-1200x1600.jpeg 1200w, https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Step_5.0-scaled-e1581341156909.jpeg 1920w\" sizes=\"auto, (max-width: 639px) 98vw, (max-width: 1199px) 64vw, 768px\" \/><\/figure><\/li><\/ul><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Zubereitung<\/h2>\n\n\n\n<p>Zun\u00e4chst die zwei Koteletts in 1,5 cm dicke Schnitzel schneiden.<\/p>\n\n\n\n<p>Als n\u00e4chstes das Fleisch mit Frischhaltefolie abdecken und mit einem Nudelholz ca. 0,5 cm flach, klopfen. Das Klopfen des Fleisches bricht die Fleischfaser auf und verhindert so, dass sich das Schnitzel beim Braten zusammenzieht. Wenn Sie lieber einen Fleischklopfer verwenden, empfehlen wir Ihnen, anstelle des Fleisches, das Schneidebrett mit Frischhaltefolie abzudecken. Auf diese Weise wird vermieden, dass kleine Teile der Frischhaltefolie an Ihren Lebensmittel kleben bleiben. Danach das Fleisch mit Salz und Pfeffer w\u00fcrzen.<\/p>\n\n\n\n<p>Nun drei Teller mit Mehl, verquirlten Eiern und Semmelbr\u00f6seln vorbereiten. Die Reihenfolge ist dabei sehr wichtig. Zuerst das Fleisch in das Mehl w\u00e4lzen, bis es vollst\u00e4ndig bedeckt ist, gefolgt von Ei und Semmelbr\u00f6sel. Wenn gew\u00fcnscht, die letzten zwei Vorg\u00e4nge wiederholen, um eine dickere Panade zu erhalten.<\/p>\n\n\n\n<p>Danach ist es Zeit, die Schnitzel zu braten. Daf\u00fcr eine Pfanne mit 50gr Butter und \u00d6l erhitzen. Die Schnitzel auf jeder Seite ca. 3 Minuten anbraten, bis die Panade goldbraun und knusprig ist. Sichersrtellen, dass w\u00e4hrend des Anbratens immer wieder Butter hinzugegeben wird.<\/p>\n\n\n\n<p>Sobald die Schnitzel fertig gebraten sind, aus der Pfanne nehmen und mit Zitrone, eventuell Meerrettich und Kapern, anrichten. Als Beilage empfehlen wir Bratkartoffeln, Erbsen, Buttersauce und extra Zitrone.<\/p>\n\n\n\n<p><strong>Frohes Kochen &amp; Guten Appetit.<\/strong><br><\/p>\n\n\n\n\n<section id=\"infoblock-block_5e4a71b544480\" class=\"infobox gray\">\n  \n  <div class=\"infobox-content\">\n                  <h1 class=\"heading\">Wildschwein Schnitzel<\/h1>\n     \n                  <a class=\"button secondary hollow\" href=\"https:\/\/blogs.zeiss.com\/intern\/sportsoptics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/Wild_Boar_Schnitzle_DE.pdf\">ZUM REZEPT<\/a>\n        <\/div>\n   \n\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Wildschweine verursachen grosse Sch\u00e4den in der Land- und Forstwirtschaft. Das Fleisch ist sehr cholesterinarm und gesunde Alternative zu Rind und Schwein.<\/p>\n","protected":false},"author":29,"featured_media":905,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[137,138],"topics":[121],"yst_prominent_words":[298,299,300,301,302,303,304,305,306,9,307,11,308,12,309,14,310,23,67,297],"class_list":["post-446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wildgerichte","tag-wildgerichte","tag-mette-karin-petersen","topics-wildgerichte"],"acf":[],"author_meta":{"display_name":"Mette Karin Petersen","author_link":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/author\/mettekarinpetersen2\/"},"featured_img":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-content\/uploads\/sites\/3\/2020\/02\/boarschnitzel_450wide-600x270.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/category\/wildgerichte\/\" class=\"advgb-post-tax-term\">Wildgerichte<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Wildgerichte<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/category\/wildgerichte\/\" class=\"advgb-post-tax-term\">Wildgerichte<\/a>","<a href=\"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/category\/wildgerichte\/\" class=\"advgb-post-tax-term\">Mette Karin Petersen<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Wildgerichte<\/span>","<span class=\"advgb-post-tax-term\">Mette Karin Petersen<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 8\u00a0Jahren ago","modified":"Updated 7\u00a0Jahren ago"},"absolute_dates":{"created":"Posted on Oktober 22, 2018","modified":"Updated on Februar 21, 2020"},"absolute_dates_time":{"created":"Posted on Oktober 22, 2018 11:01 a.m.","modified":"Updated on Februar 21, 2020 10:38 a.m."},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/posts\/446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/comments?post=446"}],"version-history":[{"count":15,"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/posts\/446\/revisions"}],"predecessor-version":[{"id":906,"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/posts\/446\/revisions\/906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/media\/905"}],"wp:attachment":[{"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/media?parent=446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/categories?post=446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/tags?post=446"},{"taxonomy":"topics","embeddable":true,"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/topics?post=446"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/blogs.zeiss.com\/sports-optics\/hunting\/de\/wp-json\/wp\/v2\/yst_prominent_words?post=446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}